{"id":7,"date":"2014-08-25T10:10:48","date_gmt":"2014-08-25T10:10:48","guid":{"rendered":"http:\/\/notas.arquitectosve.com.ar\/arquitecto-x-hora-7.htm"},"modified":"2014-08-25T17:16:39","modified_gmt":"2014-08-25T17:16:39","slug":"arquitecto-x-hora","status":"publish","type":"post","link":"https:\/\/arquitectosve.com.ar\/notas\/arquitecto-x-hora-7.htm","title":{"rendered":"Arquitecto X hora"},"content":{"rendered":"<p>Cu\u00e1ntas veces necesitaste cambiar cer\u00e1micas de un ba\u00f1o o cocina, y no sab\u00edas como combinarlas, o qu\u00e9 cantidad comprar, o d\u00f3nde conseguirlas m\u00e1s barato (generalmente es el vendedor el que termina asesor\u00e1ndote en el gusto y combinaciones&#8230;..y los resultados son inciertos).<\/p>\n<p>Ten\u00e9s ganas de cambiar los muebles de cocina y no sabes d\u00f3nde comprarlos, o c\u00f3mo hacer la distribuci\u00f3n para un mejor rendimiento.<\/p>\n<p>\u00bfQuer\u00e9s comprar un lote, pero no est\u00e1s muy seguro de hacer la elecci\u00f3n correcta, y dudas en contratar a un arquitecto para que te asesore?<\/p>\n<p>\u00bfTen\u00e9s dos anteproyectos y no pod\u00e9s evaluar cu\u00e1l es el mejor?<\/p>\n<p>\u00bfNecesit\u00e1s pintar tu casa y no sab\u00e9s qu\u00e9 colores usar?<\/p>\n<p>\u00bfEst\u00e1s por comprar una casa usada, pero no sab\u00e9s si est\u00e1 bien construida, si se puede ampliar para adaptarse a tus necesidades&#8230;. y no ten\u00e9s qui\u00e9n te asesore.?<\/p>\n<p>\u00bfQuer\u00e9s hacer una modificaci\u00f3n peque\u00f1a, ten\u00e9s el alba\u00f1il para hacerlo, pero no est\u00e1s muy convencido de hacer lo correcto.?<\/p>\n<p>Bueno, ahora todas esas peque\u00f1as (pero muy importates) consultas, las pod\u00e9s realizar sin necesidad de contratar un arquitecto para toda la obra, ni por tanto tiempo.<\/p>\n<p>Ahora podes ahorrar $$ y disgustos por no saber.<\/p>\n<p>Percibimos que hay un espacio vac\u00edo por las necesidades antes enumeradas, y ante la cantidad de consultas recibidas, nuestro estudio ha creado un departamento especial, que atiende esos \u201cpeque\u00f1os grandes\u201d inconvenientes y dudas.<\/p>\n<p>S\u00f3lo ten\u00e9s que pagar por hora, los servicios de un arquitecto\/a, que te va a asesorar y\/o acompa\u00f1ar en la compra de materiales (revestimientos, grifer\u00edas, etc.)<\/p>\n<p>No se olviden&#8230;&#8230;mejor con un <a title=\"Estudio de arquitectura\" href=\"http:\/\/www.arquitectosve.com.ar\">arquitecto<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cu\u00e1ntas veces necesitaste cambiar cer\u00e1micas de un ba\u00f1o o cocina, y no sab\u00edas como combinarlas, o qu\u00e9 cantidad comprar, o d\u00f3nde conseguirlas m\u00e1s barato (generalmente es el vendedor el que termina asesor\u00e1ndote en el gusto y combinaciones&#8230;..y los resultados son inciertos). Ten\u00e9s ganas de cambiar los muebles de cocina y no sabes d\u00f3nde comprarlos, o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[396],"tags":[34,35,42,131,250,309,312],"class_list":["post-7","post","type-post","status-publish","format-standard","hentry","category-notas","tag-arquitecto","tag-arquitecto-por-hora","tag-asesoria","tag-direccion","tag-obra","tag-profesional","tag-proyecto"],"views":10311,"_links":{"self":[{"href":"https:\/\/arquitectosve.com.ar\/notas\/wp-json\/wp\/v2\/posts\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arquitectosve.com.ar\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arquitectosve.com.ar\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arquitectosve.com.ar\/notas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arquitectosve.com.ar\/notas\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":0,"href":"https:\/\/arquitectosve.com.ar\/notas\/wp-json\/wp\/v2\/posts\/7\/revisions"}],"wp:attachment":[{"href":"https:\/\/arquitectosve.com.ar\/notas\/wp-json\/wp\/v2\/media?parent=7"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arquitectosve.com.ar\/notas\/wp-json\/wp\/v2\/categories?post=7"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arquitectosve.com.ar\/notas\/wp-json\/wp\/v2\/tags?post=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}